{"id":145,"date":"2008-01-10T16:42:19","date_gmt":"2008-01-10T15:42:19","guid":{"rendered":"https:\/\/www.1a-photoshop.de\/news\/schnee-im-gegenlicht\/"},"modified":"2008-02-11T17:14:38","modified_gmt":"2008-02-11T16:14:38","slug":"schnee-im-gegenlicht","status":"publish","type":"post","link":"https:\/\/www.1a-photoshop.de\/news\/schnee-im-gegenlicht\/","title":{"rendered":"Schnee im Gegenlicht"},"content":{"rendered":"<p>Vor einigen Jahrzehnten fing ich an, Aufnahmen bewusst mit der Sonne als Gegen\u00fcber zu gestalten. Damals fragten noch viele, was das denn soll.<!--more--> Es entsprach nicht den damaligen Sehgewohnheiten. Heute sind Gegenlicht-Aufnahmen wie diese hier von Arvid Peschel, viel \u00fcblicher geworden. Ich kann mich heute noch f\u00fcr diese Fotos begeistern und werde es auch immer wieder tun.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.1a-photoshop.de\/news\/wp-content\/zip\/gegenlicht-im-schnee.zip\"><img decoding=\"async\" alt=\"Schnee im Gegenlicht - kostenlos downloaden\" title=\"Schnee im Gegenlicht - kostenlos downloaden\"  src=\"https:\/\/www.1a-photoshop.de\/news\/wp-content\/bilder\/gegenlicht-im-schnee.jpg\" class=\"blogfoto\" \/><img decoding=\"async\" alt=\"kostenloser-download\" title=\"kostenloser-download\" src=\"https:\/\/www.1a-photoshop.de\/news\/wp-content\/bilder\/download.gif\" class=\"download\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor einigen Jahrzehnten fing ich an, Aufnahmen bewusst mit der Sonne als Gegen\u00fcber zu gestalten. Damals fragten noch viele, was das denn soll.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-145","post","type-post","status-publish","format-standard","hentry","category-gratis-bilder"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/posts\/145"}],"collection":[{"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":0,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/posts\/145\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/media?parent=145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/categories?post=145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/tags?post=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}