{"id":294,"date":"2008-04-29T23:13:19","date_gmt":"2008-04-29T21:13:19","guid":{"rendered":"https:\/\/www.1a-photoshop.de\/news\/neugieriges-schaf\/"},"modified":"2008-04-29T23:13:19","modified_gmt":"2008-04-29T21:13:19","slug":"neugieriges-schaf","status":"publish","type":"post","link":"https:\/\/www.1a-photoshop.de\/news\/neugieriges-schaf\/","title":{"rendered":"Neugieriges Schaf"},"content":{"rendered":"<p>Wusste ich\u00c2\u00b4s doch &#8211; Schafsschnauzen sind rosa! Dieses neugierige Schaf lebt mit ein paar Gef\u00e4hrten in Berlin-Marzahn, zu F\u00fc\u00dfen der Bockwindm\u00fchle. Eigentlich sind<!--more--> die wolligen Tiere ja scheu und passiv und eher desinteressiert am Geschehen ringsum. Lassen sich ohne Gegenwehr scheren und sogar schlachten &#8211; echte Opfer halt. Das Sch\u00e4fchen hier scheint eine Ausnahme zu sein &#8211; gef\u00e4llt mir. Die gro\u00dfe, weite Welt hat seiner Schafsschnauze doch sicher noch mehr zu bieten als den Duft von Gras, Schafsk\u00f6tteln und Marzahner Auto-Abgasen!<br \/>\n(Text: Kathrin Peschel; Foto &#038; \u00a9 Viktor Peschel)<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.1a-photoshop.de\/news\/wp-content\/zip\/schaf-und-zaun.zip\"><br \/>\n<img decoding=\"async\" alt=\"Schaf - Schafsschnauze\" title=\"Schaf - Schafsschnauze\" src=\"https:\/\/www.1a-photoshop.de\/news\/wp-content\/bilder\/schaf-und-zaun.jpg\" class=\"blogfoto\" \/><br \/>\n<img decoding=\"async\" alt=\"kostenloser-download\"  title=\"kostenloser-download\" src=\"https:\/\/www.1a-photoshop.de\/news\/wp-content\/bilder\/download.gif\" class=\"download\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wusste ich\u00c2\u00b4s doch &#8211; Schafsschnauzen sind rosa! Dieses neugierige Schaf lebt mit ein paar Gef\u00e4hrten in Berlin-Marzahn, zu F\u00fc\u00dfen der Bockwindm\u00fchle. Eigentlich sind<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-294","post","type-post","status-publish","format-standard","hentry","category-gratis-bilder"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/posts\/294"}],"collection":[{"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/comments?post=294"}],"version-history":[{"count":0,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/posts\/294\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/media?parent=294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/categories?post=294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.1a-photoshop.de\/news\/wp-json\/wp\/v2\/tags?post=294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}